{"id":2078,"date":"2012-04-27T12:13:28","date_gmt":"2012-04-27T11:13:28","guid":{"rendered":"http:\/\/j-mad.com\/blog\/?p=2078"},"modified":"2012-07-16T09:59:24","modified_gmt":"2012-07-16T07:59:24","slug":"retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril","status":"publish","type":"post","link":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/","title":{"rendered":"Retour des liens de la semaine, ceux du vendredi 27 avril"},"content":{"rendered":"<p>Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, <a href=\"http:\/\/www.scoop.it\/t\/les-liens-de-mrjmad\" target=\"_blank\">un scoop.it<\/a> pour pouvoir partager les liens en temps r\u00e9els (mais garder un historique des choses) et un billet recap chaque semaine (ou presque).<\/p>\n<p>Voila, voila, une fois cette petite nouveaut\u00e9 expliqu\u00e9e, voici les liens :<\/p>\n<ul>\n<li><a href=\"http:\/\/www.tobechanged.com\/1075-taux-de-clic-plus-une-banniere-est-moche-plus-elle-intrigue.html\" target=\"_blank\">Plus une banni\u00e8re est moche, plus elle intrigue ..<\/a><\/li>\n<li><a href=\"http:\/\/issuu.com\/futurenoir\/docs\/bladerunner_sketchbook\" target=\"_blank\">le sketchbook de Blade Runner<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=KJ261Ztnf6A\" target=\"_blank\">petite vid\u00e9o pour rire, un remix de la chanson Vid\u00e9o Games<\/a><\/li>\n<li><a href=\"http:\/\/releases.ubuntu.com\/precise\/\" target=\"_blank\">la nouvelle version d&#8217;ubuntu<\/a><\/li>\n<li><a href=\"http:\/\/blog.exirel.me\/faire-des-trucs\" target=\"_blank\">Faire des trucs<\/a> d&#8217;Exirel et <a href=\"http:\/\/thebestplace.fr\/2012\/04\/09\/1268-envy\/\" target=\"_blank\">Envy<\/a> de LeReilly, deux liens sur le m\u00eame sujet, l&#8217;envie de faire des choses et le comment en trouver la motivation<\/li>\n<li>le trailer de <a href=\"https:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=Ac5zNHLEQp8#!\" target=\"_blank\">Brave<\/a>, le prochain PIXAR<\/li>\n<li><a href=\"http:\/\/www.lepoint.fr\/societe\/l-etat-americain-du-connecticut-abolit-la-peine-de-mort-25-04-2012-1455239_23.php\" target=\"_blank\">l&#8217;\u00e9tat du Connecticut qui aboli la peine de mort &#8230;<\/a><\/li>\n<li><a href=\"http:\/\/english.alarabiya.net\/articles\/2012\/04\/25\/210198.html\" target=\"_blank\">ca se passe en \u00e9gypte &#8230; (j&#8217;aimerais vraiment qu&#8217;on me dise que c&#8217;est un canular &#8230; )\u00a0<\/a><\/li>\n<li><a href=\"http:\/\/www.webupd8.org\/2012\/04\/valvle-works-on-steam-for-linux.html\">Steam sous linux, bient\u00f4t \u00e7a ne sera plus juste un r\u00eave (ou un cauchemar)<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=kNUBV9trDoA\" target=\"_blank\">Le trailer d&#8217;un futur navet GI Joe 2 &#8230;<\/a><\/li>\n<li><a href=\"http:\/\/www.walrus-books.com\/2012\/04\/menu-cthulhu-une-nouvelle-dont-vous-etes-le-heros\/\" target=\"_blank\">un livre dont vous \u00eates le h\u00e9ros en Epub !!<\/a><\/li>\n<li><a href=\"http:\/\/www.grimrock.net\/\" target=\"_blank\">Legend of Grimrock , en voila un jeu qu&#8217;il est bien !!!<\/a><\/li>\n<li><a href=\"http:\/\/www.lemonde.fr\/europe\/article\/2012\/04\/26\/des-milliers-de-norvegiens-veulent-desavouer-breivik-en-interpretant-une-chanson-qu-il-hait_1691225_3214.html\" target=\"_blank\">Quand les norv\u00e9giens chantent des comptines sous la pluie &#8230;<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it &hellip; <a href=\"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Retour des liens de la semaine, ceux du vendredi 27 avril<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[94],"tags":[],"class_list":["post-2078","post","type-post","status-publish","format-standard","hentry","category-trucs-et-vrac"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"J-Mad\"\/>\n\t<meta name=\"keywords\" content=\"trucs et vrac\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le Mad Blog | juste un blog\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-04-27T11:13:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-07-16T07:59:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#article\",\"name\":\"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog\",\"headline\":\"Retour des liens de la semaine, ceux du vendredi 27 avril\",\"author\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#organization\"},\"datePublished\":\"2012-04-27T12:13:28+02:00\",\"dateModified\":\"2012-07-16T09:59:24+02:00\",\"inLanguage\":\"fr-fr\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#webpage\"},\"articleSection\":\"Trucs et Vrac\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/j-mad.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/#listItem\",\"name\":\"De tout et de rien\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/#listItem\",\"position\":2,\"name\":\"De tout et de rien\",\"item\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/#listItem\",\"name\":\"Trucs et Vrac\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/#listItem\",\"position\":3,\"name\":\"Trucs et Vrac\",\"item\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#listItem\",\"name\":\"Retour des liens de la semaine, ceux du vendredi 27 avril\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/#listItem\",\"name\":\"De tout et de rien\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#listItem\",\"position\":4,\"name\":\"Retour des liens de la semaine, ceux du vendredi 27 avril\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/#listItem\",\"name\":\"Trucs et Vrac\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#organization\",\"name\":\"Le Mad Blog\",\"description\":\"juste un blog\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/\",\"name\":\"J-Mad\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eb44e8eb2792583de23c66deb033f8b5ef4f7f7c535464d77cb9f643012d138?s=96&d=retro&r=g\",\"width\":96,\"height\":96,\"caption\":\"J-Mad\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#webpage\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/\",\"name\":\"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog\",\"description\":\"Apr\\u00e8s quelques semaines de pure folie (et avant que \\u00e7a ne recommence de m\\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it\",\"inLanguage\":\"fr-fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2012\\\/04\\\/27\\\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\"},\"datePublished\":\"2012-04-27T12:13:28+02:00\",\"dateModified\":\"2012-07-16T09:59:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/\",\"name\":\"Le Mad Blog\",\"description\":\"juste un blog\",\"inLanguage\":\"fr-fr\",\"publisher\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog","description":"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it","canonical_url":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/","robots":"max-image-preview:large","keywords":"trucs et vrac","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#article","name":"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog","headline":"Retour des liens de la semaine, ceux du vendredi 27 avril","author":{"@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author"},"publisher":{"@id":"https:\/\/j-mad.com\/blog\/#organization"},"datePublished":"2012-04-27T12:13:28+02:00","dateModified":"2012-07-16T09:59:24+02:00","inLanguage":"fr-fr","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#webpage"},"isPartOf":{"@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#webpage"},"articleSection":"Trucs et Vrac"},{"@type":"BreadcrumbList","@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/j-mad.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/#listItem","name":"De tout et de rien"}},{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/#listItem","position":2,"name":"De tout et de rien","item":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/","nextItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/#listItem","name":"Trucs et Vrac"},"previousItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/#listItem","position":3,"name":"Trucs et Vrac","item":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/","nextItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#listItem","name":"Retour des liens de la semaine, ceux du vendredi 27 avril"},"previousItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/#listItem","name":"De tout et de rien"}},{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#listItem","position":4,"name":"Retour des liens de la semaine, ceux du vendredi 27 avril","previousItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/#listItem","name":"Trucs et Vrac"}}]},{"@type":"Organization","@id":"https:\/\/j-mad.com\/blog\/#organization","name":"Le Mad Blog","description":"juste un blog","url":"https:\/\/j-mad.com\/blog\/"},{"@type":"Person","@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author","url":"https:\/\/j-mad.com\/blog\/author\/j-mad\/","name":"J-Mad","image":{"@type":"ImageObject","@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6eb44e8eb2792583de23c66deb033f8b5ef4f7f7c535464d77cb9f643012d138?s=96&d=retro&r=g","width":96,"height":96,"caption":"J-Mad"}},{"@type":"WebPage","@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#webpage","url":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/","name":"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog","description":"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it","inLanguage":"fr-fr","isPartOf":{"@id":"https:\/\/j-mad.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/#breadcrumblist"},"author":{"@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author"},"creator":{"@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author"},"datePublished":"2012-04-27T12:13:28+02:00","dateModified":"2012-07-16T09:59:24+02:00"},{"@type":"WebSite","@id":"https:\/\/j-mad.com\/blog\/#website","url":"https:\/\/j-mad.com\/blog\/","name":"Le Mad Blog","description":"juste un blog","inLanguage":"fr-fr","publisher":{"@id":"https:\/\/j-mad.com\/blog\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le Mad Blog | juste un blog","og:type":"article","og:title":"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog","og:description":"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it","og:url":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/","article:published_time":"2012-04-27T11:13:28+00:00","article:modified_time":"2012-07-16T07:59:24+00:00","twitter:card":"summary","twitter:title":"Retour des liens de la semaine, ceux du vendredi 27 avril | Le Mad Blog","twitter:description":"Apr\u00e8s quelques semaines de pure folie (et avant que \u00e7a ne recommence de m\u00eame, voir pire), je relance les liens de la semaine. Une petite modification toutefois, cela me frustrait pas mal de devoir attendre une semaine pour partager les liens que je trouvais. Du coup, je vais mettre en place deux choses, un scoop.it"},"aioseo_meta_data":{"post_id":"2078","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 21:05:10","updated":"2025-06-03 22:08:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/j-mad.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/\" title=\"De tout et de rien\">De tout et de rien<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/\" title=\"Trucs et Vrac\">Trucs et Vrac<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRetour des liens de la semaine, ceux du vendredi 27 avril\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/j-mad.com\/blog"},{"label":"De tout et de rien","link":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/"},{"label":"Trucs et Vrac","link":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/"},{"label":"Retour des liens de la semaine, ceux du vendredi 27 avril","link":"https:\/\/j-mad.com\/blog\/2012\/04\/27\/retour-des-liens-de-la-semaine-ceux-du-vendredi-27-avril\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p12cdp-xw","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts\/2078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/comments?post=2078"}],"version-history":[{"count":10,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts\/2078\/revisions"}],"predecessor-version":[{"id":2206,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts\/2078\/revisions\/2206"}],"wp:attachment":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/media?parent=2078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/categories?post=2078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/tags?post=2078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}