{"id":1721,"date":"2011-10-21T12:28:39","date_gmt":"2011-10-21T11:28:39","guid":{"rendered":"http:\/\/j-mad.com\/blog\/?p=1721"},"modified":"2011-11-12T19:23:20","modified_gmt":"2011-11-12T18:23:20","slug":"semaine-du-22-octobre","status":"publish","type":"post","link":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/","title":{"rendered":"Semaine du 21 octobre"},"content":{"rendered":"<p>Une nouvelle semaine, un nouveau billet rempli de liens sympas :<\/p>\n<ul>\n<li>\u00a0quand <a href=\"http:\/\/www.rue89.com\/2011\/10\/15\/petit-je-voulais-etre-boulanger-mais-jetais-bon-en-maths-225582\" target=\"_blank\">Rue89 parle de l&#8217;\u00e9cole<\/a> &#8230; je ne pourrais pas dire qu&#8217;ils ont tord&#8230;<\/li>\n<li>les <a href=\"http:\/\/www.youtube.com\/watch?v=Ws6AAhTw7RA\" target=\"_blank\">voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0<\/a><\/li>\n<li>la <a href=\"http:\/\/www.france-info.com\/france-justice-police-2011-10-19-ecoutes-en-libye-la-fidh-porte-plainte-contre-la-societe-francaise-569702-9-11.html\" target=\"_blank\">FDIH porte plainte contre Amesys<\/a><\/li>\n<li><a href=\"http:\/\/librelist.com\/\" target=\"_blank\">librelist<\/a>, ou comment faire des mailings list publique facilement.<\/li>\n<li><a href=\"http:\/\/www.lanouvellerepublique.fr\/ACTUALITE\/People\/Nicolas-Carla-et-le-bebe-chronique-d-une-delivrance\" target=\"_blank\">un pr\u00e9sident qui devient papa<\/a>. (le fait est suffisamment rare pour \u00eatre not\u00e9)<\/li>\n<li><a href=\"http:\/\/tempsreel.nouvelobs.com\/monde\/20111020.FAP6899\/kadhafi-est-tue-dans-la-chute-de-son-dernier-bastion.html\" target=\"_blank\">la mort de Khadhafi<\/a><\/li>\n<li><a href=\"http:\/\/www.lepoint.fr\/monde\/l-eta-annonce-la-fin-de-la-lutte-armee-20-10-2011-1387101_24.php\" target=\"_blank\">l&#8217;ETA cesse la lutte arm\u00e9e.<\/a><\/li>\n<li><a href=\"http:\/\/worrydream.com\/Tangle\/\" target=\"_blank\">Tangle<\/a>, une librairie js sympa<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle semaine, un nouveau billet rempli de liens sympas : \u00a0quand Rue89 parle de l&#8217;\u00e9cole &#8230; je ne pourrais pas dire qu&#8217;ils ont tord&#8230; les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment &hellip; <a href=\"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Semaine du 21 octobre<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[94],"tags":[],"class_list":["post-1721","post","type-post","status-publish","format-standard","hentry","category-trucs-et-vrac"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l&#039;\u00e9cole ... je ne pourrais pas dire qu&#039;ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"J-Mad\"\/>\n\t<meta name=\"keywords\" content=\"trucs et vrac\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le Mad Blog | juste un blog\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Semaine du 21 octobre | Le Mad Blog\" \/>\n\t\t<meta property=\"og:description\" content=\"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l&#039;\u00e9cole ... je ne pourrais pas dire qu&#039;ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-10-21T11:28:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-11-12T18:23:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Semaine du 21 octobre | Le Mad Blog\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l&#039;\u00e9cole ... je ne pourrais pas dire qu&#039;ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#article\",\"name\":\"Semaine du 21 octobre | Le Mad Blog\",\"headline\":\"Semaine du 21 octobre\",\"author\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#organization\"},\"datePublished\":\"2011-10-21T12:28:39+02:00\",\"dateModified\":\"2011-11-12T19:23:20+01:00\",\"inLanguage\":\"fr-fr\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#webpage\"},\"articleSection\":\"Trucs et Vrac\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/j-mad.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/#listItem\",\"name\":\"De tout et de rien\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/#listItem\",\"position\":2,\"name\":\"De tout et de rien\",\"item\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/#listItem\",\"name\":\"Trucs et Vrac\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/#listItem\",\"position\":3,\"name\":\"Trucs et Vrac\",\"item\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#listItem\",\"name\":\"Semaine du 21 octobre\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/#listItem\",\"name\":\"De tout et de rien\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#listItem\",\"position\":4,\"name\":\"Semaine du 21 octobre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/category\\\/de-tout-et-de-rien\\\/trucs-et-vrac\\\/#listItem\",\"name\":\"Trucs et Vrac\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#organization\",\"name\":\"Le Mad Blog\",\"description\":\"juste un blog\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/\",\"name\":\"J-Mad\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6eb44e8eb2792583de23c66deb033f8b5ef4f7f7c535464d77cb9f643012d138?s=96&d=retro&r=g\",\"width\":96,\"height\":96,\"caption\":\"J-Mad\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#webpage\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/\",\"name\":\"Semaine du 21 octobre | Le Mad Blog\",\"description\":\"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l'\\u00e9cole ... je ne pourrais pas dire qu'ils ont tord... les voitures volantes sont bient\\u00f4t l\\u00e0\\u00e0\\u00e0\\u00e0\\u00e0\\u00e0\\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\\u00e9sident qui devient papa. (le fait est suffisamment\",\"inLanguage\":\"fr-fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/2011\\\/10\\\/21\\\/semaine-du-22-octobre\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/author\\\/j-mad\\\/#author\"},\"datePublished\":\"2011-10-21T12:28:39+02:00\",\"dateModified\":\"2011-11-12T19:23:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/\",\"name\":\"Le Mad Blog\",\"description\":\"juste un blog\",\"inLanguage\":\"fr-fr\",\"publisher\":{\"@id\":\"https:\\\/\\\/j-mad.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Semaine du 21 octobre | Le Mad Blog","description":"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l'\u00e9cole ... je ne pourrais pas dire qu'ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment","canonical_url":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/","robots":"max-image-preview:large","keywords":"trucs et vrac","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#article","name":"Semaine du 21 octobre | Le Mad Blog","headline":"Semaine du 21 octobre","author":{"@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author"},"publisher":{"@id":"https:\/\/j-mad.com\/blog\/#organization"},"datePublished":"2011-10-21T12:28:39+02:00","dateModified":"2011-11-12T19:23:20+01:00","inLanguage":"fr-fr","mainEntityOfPage":{"@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#webpage"},"isPartOf":{"@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#webpage"},"articleSection":"Trucs et Vrac"},{"@type":"BreadcrumbList","@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/j-mad.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/#listItem","name":"De tout et de rien"}},{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/#listItem","position":2,"name":"De tout et de rien","item":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/","nextItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/#listItem","name":"Trucs et Vrac"},"previousItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/#listItem","position":3,"name":"Trucs et Vrac","item":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/","nextItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#listItem","name":"Semaine du 21 octobre"},"previousItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/#listItem","name":"De tout et de rien"}},{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#listItem","position":4,"name":"Semaine du 21 octobre","previousItem":{"@type":"ListItem","@id":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/#listItem","name":"Trucs et Vrac"}}]},{"@type":"Organization","@id":"https:\/\/j-mad.com\/blog\/#organization","name":"Le Mad Blog","description":"juste un blog","url":"https:\/\/j-mad.com\/blog\/"},{"@type":"Person","@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author","url":"https:\/\/j-mad.com\/blog\/author\/j-mad\/","name":"J-Mad","image":{"@type":"ImageObject","@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6eb44e8eb2792583de23c66deb033f8b5ef4f7f7c535464d77cb9f643012d138?s=96&d=retro&r=g","width":96,"height":96,"caption":"J-Mad"}},{"@type":"WebPage","@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#webpage","url":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/","name":"Semaine du 21 octobre | Le Mad Blog","description":"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l'\u00e9cole ... je ne pourrais pas dire qu'ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment","inLanguage":"fr-fr","isPartOf":{"@id":"https:\/\/j-mad.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/#breadcrumblist"},"author":{"@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author"},"creator":{"@id":"https:\/\/j-mad.com\/blog\/author\/j-mad\/#author"},"datePublished":"2011-10-21T12:28:39+02:00","dateModified":"2011-11-12T19:23:20+01:00"},{"@type":"WebSite","@id":"https:\/\/j-mad.com\/blog\/#website","url":"https:\/\/j-mad.com\/blog\/","name":"Le Mad Blog","description":"juste un blog","inLanguage":"fr-fr","publisher":{"@id":"https:\/\/j-mad.com\/blog\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le Mad Blog | juste un blog","og:type":"article","og:title":"Semaine du 21 octobre | Le Mad Blog","og:description":"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l'\u00e9cole ... je ne pourrais pas dire qu'ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment","og:url":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/","article:published_time":"2011-10-21T11:28:39+00:00","article:modified_time":"2011-11-12T18:23:20+00:00","twitter:card":"summary","twitter:title":"Semaine du 21 octobre | Le Mad Blog","twitter:description":"Une nouvelle semaine, un nouveau billet rempli de liens sympas : quand Rue89 parle de l'\u00e9cole ... je ne pourrais pas dire qu'ils ont tord... les voitures volantes sont bient\u00f4t l\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0\u00e0 la FDIH porte plainte contre Amesys librelist, ou comment faire des mailings list publique facilement. un pr\u00e9sident qui devient papa. (le fait est suffisamment"},"aioseo_meta_data":{"post_id":"1721","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 21:12:20","updated":"2025-06-03 22:04:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/j-mad.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/\" title=\"De tout et de rien\">De tout et de rien<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/\" title=\"Trucs et Vrac\">Trucs et Vrac<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSemaine du 21 octobre\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/j-mad.com\/blog"},{"label":"De tout et de rien","link":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/"},{"label":"Trucs et Vrac","link":"https:\/\/j-mad.com\/blog\/category\/de-tout-et-de-rien\/trucs-et-vrac\/"},{"label":"Semaine du 21 octobre","link":"https:\/\/j-mad.com\/blog\/2011\/10\/21\/semaine-du-22-octobre\/"}],"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p12cdp-rL","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":12,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":1789,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/posts\/1721\/revisions\/1789"}],"wp:attachment":[{"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/j-mad.com\/blog\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}